{"id":10722,"date":"2024-04-10T09:32:33","date_gmt":"2024-04-10T00:32:33","guid":{"rendered":"https:\/\/dancebase.yokohama\/creator\/residence_artist\/2022-2"},"modified":"2024-11-25T14:54:32","modified_gmt":"2024-11-25T05:54:32","slug":"archive2023","status":"publish","type":"page","link":"https:\/\/dancebase.yokohama\/en\/creator\/residence_artist\/archive2023\/","title":{"rendered":"2023"},"content":{"rendered":"<div class=\"container\">\n\t<div class=\"row pb-78px strong50\">\n\t\t<div class=\"col-12\">\n\t\t\t<ul class=\"page-tab\">\n\t\t\t\t<li><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator\/creative_staff\">Creative Staff<\/a><\/li>\n\t\t\t\t<li><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator\/residence_artist\">Resident Artist<\/a><br>\n\t\t\t\t\t<ul class=\"drop\">\n\t\t\t\t\t\t<li><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator\/residence_artist\/archive2023\">2023<\/a><\/li>\n\t\t\t\t\t\t<li><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator\/residence_artist\/archive2022\">2022<\/a><\/li>\n\t\t\t\t\t\t<li><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator\/residence_artist\/archive2021\">2021<\/a><\/li>\n\t\t\t\t\t\t<li><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator\/residence_artist\/archive2020\">2020<\/a><\/li>\n\t\t\t\t\t<\/ul>\n\t\t\t\t<\/li>\n\t\t\t\t<li><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator\/commission_artist\">Guest Artists<\/a><\/li>\n\t\t\t<\/ul>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"text-left pb-39px\">\n\t<h3 class=\"h3-title\">Resident Artist<\/h3>\n<\/div>\n<div class=\"container pt-0 pl-0 pr-0\">\n\t<div class=\"row commissionartist-list no0525\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<div class=\"row row-50\">\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/teita-iwabuchi\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2021\/01\/teitaiwabuchi.jpg\" alt=\"Teita Iwabuchi\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0eSakiko Nomura<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/teita-iwabuchi\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Teita Iwabuchi<\/div>\n\t\t\t\t\t<div class=\"en-name\">Teita Iwabuchi<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/mariko-kakizaki\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/04\/MarikoKakizaki2-scaled.jpg\" alt=\"Mariko Kakizaki\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0emorikohga<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/mariko-kakizaki\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Mariko Kakizaki<\/div>\n\t\t\t\t\t<div class=\"en-name\">Mariko Kakizaki<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/kaho-kogure\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/04\/KahoKogure.jpeg\" alt=\"Kaho Kogure\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9Toshiaki Kitaoka<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/kaho-kogure\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Kaho Kogure<\/div>\n\t\t\t\t\t<div class=\"en-name\">Kaho Kogure<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/kenta-kojiri\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/04\/KentaKojiri.jpeg\" alt=\"Kenta Kojiri\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9Carl Thorborg<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/kenta-kojiri\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Kenta Koyurugi<\/div>\n\t\t\t\t\t<div class=\"en-name\">Kenta Kojiri<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/yo-nakamura\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/04\/YoNakamura.jpeg\" alt=\"Yo Nakamura\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0e Hideto Maezawa<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/yo-nakamura\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Nakamura Ryo<\/div>\n\t\t\t\t\t<div class=\"en-name\">Yo Nakamura<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/roma-hashimoto\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2021\/09\/roma-hashimoto.jpg\" alt=\"Roma Hashimoto\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/roma-hashimoto\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Rom Hashimoto<\/div>\n\t\t\t\t\t<div class=\"en-name\">Roma Hashimoto<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u6f14\u51fa\u30fb\u30d1\u30d5\u30a9\u30fc\u30df\u30f3\u30b0\u30a2\u30fc\u30c4<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/saori-hala\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2020\/09\/hala_2.jpg\" alt=\"Saori Hala | Saori Hala\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9Kazuhei Kimura<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/saori-hala\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Saori Hala<\/div>\n\t\t\t\t\t<div class=\"en-name\">Saori Hala<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9\u30fb\u7f8e\u8853<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/shintaro-hirahara\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2020\/06\/hirahara.jpg\" alt=\"Shintaro Hirahara\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9Eiji Takahashi<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/mariko-ono\/\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Shintaro Hirahara<\/div>\n\t\t\t\t\t<div class=\"en-name\">Shintaro Hirahara<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n<div class=\"text-left pb-39px\">\n\t<h3 class=\"h3-title\">2023 Open Call for Residence Artists<\/h3>\n<\/div>\n<div class=\"container pt-0 pl-0 pr-0\">\n\t<div class=\"row commissionartist-list no0525\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<div class=\"row row-50\">\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/conan-amok\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/conan.jpg\" alt=\"Conan Amok\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9Mai Taniguchi<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/conan-amok\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">flamboyant<\/div>\n\t\t\t\t\t<div class=\"en-name\">Conan Amok<\/div>\n\t\t\t\t\t<!--<div class=\"jp-genre\">\u30c0\u30f3\u30b9<\/div>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/yuki-ayato\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/ayato.jpg\" alt=\"Yuuki Ayamon | Conan Amok\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0eMiura Rain Forest<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/yuki-ayato\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Yuki Ayato<\/div>\n\t\t\t\t\t<div class=\"en-name\">Yuki Ayato<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/rion-onaya\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/rion.jpg\" alt=\"Rion Onaya (room.Onaya Rion) | Rion Onaya\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0eKoji Iida<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/rion-onaya\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Onaya Rion (room.Onaya Rion)<\/div>\n\t\t\t\t\t<div class=\"en-name\">Rion Onaya<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/spacenotblank\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/04\/Spacenotblank2022.jpg\" alt=\"Ayaka Ono Akira Nakazawa Spacenotblank\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0eDan \u00c5ke Carlsson<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/spacenotblank\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Ayaka Ono Akira Nakazawa Spacenotblank<\/div>\n\t\t\t\t\t<div class=\"en-name\">Ayaka Ono Akira Nakazawa Spacenotblank<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/naoyuki-sakai\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/sakai.jpg\" alt=\"Naoyuki Sakai\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0eShun Nakamura<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/naoyuki-sakai\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Naoyuki Sakai<\/div>\n\t\t\t\t\t<div class=\"en-name\">Naoyuki Sakai<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/koichiro-tamura\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/tamura.jpg\" alt=\"Koichiro Tamura\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0eTakashi Kanai<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/koichiro-tamura\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Koichiro Tamura<\/div>\n\t\t\t\t\t<div class=\"en-name\">Koichiro Tamura<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/akiyoshi-nita\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/nita.jpg\" alt=\"Akiyoshi Nita\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0ehalkuzuya<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/akiyoshi-nita\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Shokai Nita<\/div>\n\t\t\t\t\t<div class=\"en-name\">Akiyoshi Nita<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/maya-hashimoto\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/hashimoto.jpg\" alt=\"Mana Hashimoto | Mana Hashimoto\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0eDeer Deer Tang<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/maya-hashimoto\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Mana Hashimoto<\/div>\n\t\t\t\t\t<div class=\"en-name\">Mana Hashimoto<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/yohei-hamada\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/hamada.jpg\" alt=\"Yohei Hamada\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0eHiromasa Takahashi<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/yohei-hamada\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Yohei Hamada<\/div>\n\t\t\t\t\t<div class=\"en-name\">Yohei Hamada<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u632f\u4ed8\u30fb\u6f14\u51fa\u30fb\u30d1\u30d5\u30a9\u30fc\u30df\u30f3\u30b0\u30a2\u30fc\u30c4<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/kohei-fujimura\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2020\/10\/DSC00417-scaled-e1665044300728.jpg\" alt=\"Kohei Fujimura\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0etasukiamano<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/kohei-fujimura\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">Kohei Fujimura<\/div>\n\t\t\t\t\t<div class=\"en-name\">Kohei Fujimura<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/bala\" class=\"text-right strong20 d-block\"><br>\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/bala.jpg\" alt=\"BALA | Kohei Fujimura\" class=\"img-fluid mx-auto d-block\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0eHajime Kato<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<a href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/bala\"><br>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t<div class=\"jp-name\">BALA<\/div>\n\t\t\t\t\t<div class=\"en-name\">BALA<\/div>\n\t\t\t\t\t<br>\n\t\t\t\t\t<!--<\/p>\n\t<div class=\"jp-genre\">\u30c0\u30f3\u30b9<\/div>\n\t<p>-->\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"text-left pb-39px\">\n\t<h3 class=\"h3-title\">Resident Dancers<\/h3>\n<\/div>\n<div class=\"container pt-0 pl-0 pr-0\">\n\t<div class=\"row commissionartist-list no0525\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<div class=\"row row-50\">\n\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\">\n\t\t\t\t\t<a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/jun-aoyagi\/\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/05\/Profile_Jun-Aoyagi.jpeg\" alt=\"Jun Aoyagi | Jun Aoyagi\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Jun Aoyagi<\/div>\n\t\t\t\t\t<div class=\"en-name\">Jun Aoyagi<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/ayano-otaki\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/05\/Profile_Ayano-Otaki.jpeg\" alt=\"Ayano Otaki\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Ayano Otaki<\/div>\n\t\t\t\t\t<div class=\"en-name\">Ayano Otaki<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/riena-kashima\/\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/05\/Profile_Riena-Kashima.jpg\" alt=\"Riena Kashima | Riena Kashima\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Riena Kashima<\/div>\n\t\t\t\t\t<div class=\"en-name\">Riena Kashima<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/nono-kinouchi\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/kinouchi.jpg\" alt=\"Nono Kinouchi | Nono Kinouchi\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9Hawaka<\/div>\n\t\t\t\t\t<div class=\"jp-name\">Nono Kinouchi<\/div>\n\t\t\t\t\t<div class=\"en-name\">Nono Kinouchi<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/akane-kuri\/\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/08\/AkaneKuri_480x620_thum.jpg\" alt=\"Akane Kuri\"><\/a>\n\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t<div class=\"jp-name\">Akane Kuri<\/div>\n\t\t\t\t<div class=\"en-name\">Akane Kuri<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/hana-tsuchimoto\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/05\/Profile_hana-tsuchimoto.jpg\" alt=\"Hana Tsuchimoto\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Hana Tsutchimoto<\/div>\n\t\t\t\t\t<div class=\"en-name\">Hana Tsuchimoto<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/inoru-toda\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/05\/Profile_Inoru-Toda.jpg\" alt=\"Prayer Toda | Inoru Toda\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Toda Prayer<\/div>\n\t\t\t\t\t<div class=\"en-name\">Inoru Toda<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/ain-tominaga\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/12\/Profile_Ain-Tominaga%C2%A9%EF%B8%8EShin-Suzuki.jpg\" alt=\"Ain Tominaga\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0eShin Suzuki<\/div>\n\t\t\t\t\t<div class=\"jp-name\">Ain Tominaga<\/div>\n\t\t\t\t\t<div class=\"en-name\">Ain Tominaga<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/ayaka-nakatsu\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/05\/Profile_nakatsu.jpg\" alt=\"Ayaka Nakatsu\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Nakatsu bunkka<\/div>\n\t\t\t\t\t<div class=\"en-name\">Ayaka Nakatsu<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/ayane-nakamura\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/nakamura_a.jpg\" alt=\"Ayane Nakamura\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Ayane Nakamura<\/div>\n\t\t\t\t\t<div class=\"en-name\">Ayane Nakamura<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/mano-hatanaka\/\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/05\/Profile_Mano-Hatanaka.jpeg\" alt=\"Mano Hatanaka\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Mano Hatanaka<\/div>\n\t\t\t\t\t<div class=\"en-name\">Mano Hatanaka<\/div>\n\t\t\t\t<\/div>\n\t\t\n\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/nana-horikawa\/\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2021\/10\/horikawanana-e1665044558195.jpg\" alt=\"Nana Horikawa | Nana Horikawa\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Nana Horikawa<\/div>\n\t\t\t\t\t<div class=\"en-name\">Nana Horikawa<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/haruka-makabe\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/05\/Profile_haruka-makabe.jpg\" alt=\"Haruka Makabe | Nana Horikawa\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\">\u00a9\ufe0e Kaneko Aiho<\/div>\n\t\t\t\t\t<div class=\"jp-name\">Haruka Makabe<\/div>\n\t\t\t\t\t<div class=\"en-name\">Haruka Makabe<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/ikuma-murakami\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/04\/Profile_Ikuma-Murakami_s-scaled.jpg\" alt=\"Ikuma Murakami\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Ikuma Murakami<\/div>\n\t\t\t\t\t<div class=\"en-name\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/taisuke-yamaguchi\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2023\/05\/yamaguchi.jpg\" alt=\"Taisuke Yamaguchi\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Taisuke Yamaguchi<\/div>\n\t\t\t\t\t<div class=\"en-name\">Taisuke Yamaguchi<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"col-6 col-sm-3 pb-78px strong40\"><a class=\"text-right pb-39px strong20\" href=\"https:\/\/dancebase.yokohama\/en\/\/creator_profile\/nagisa-yoshida\/\"> <img decoding=\"async\" class=\"img-fluid mx-auto d-block\" src=\"https:\/\/dancebase.yokohama\/wp\/wp-content\/uploads\/2022\/05\/Profile_Nagisa-Yoshida.jpeg\" alt=\"Nagisa Yoshida\"><\/a>\n\t\t\t\t\t<div class=\"text-right strong20 d-block f10 pt-10px pb-39px\"><\/div>\n\t\t\t\t\t<div class=\"jp-name\">Nagisa Yoshida<\/div>\n\t\t\t\t\t<div class=\"en-name\">Nagisa Yoshida<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Creative Staff Resident Artist 2023 2022 2021 2020 Guest Artists Resident Artist \u00a9\ufe0eSakiko Nomura Teita Iwabuchi Teita Iwabuchi \u00a9\ufe0emorikohga Mariko Kakizaki Mariko Kakizaki \u00a9Toshiaki Kitaoka Kaho Kogure Kaho Kogure \u00a9Carl Thorborg Kenta Koyurugi Kenta Kojiri \u00a9\ufe0e Hideto Maezawa Nakamura Ryo Yo Nakamura Rom Hashimoto Roma Hashimoto \u00a9Kazuhei Kimura Saori Hala Saori Hala \u00a9Eiji Takahashi Shintaro [&hellip;]","protected":false},"author":5,"featured_media":0,"parent":9046,"menu_order":60,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"class_list":["post-10722","page","type-page","status-publish","hentry"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 11:21:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/dancebase.yokohama\/en\/wp-json\/wp\/v2\/pages\/10722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dancebase.yokohama\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dancebase.yokohama\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dancebase.yokohama\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/dancebase.yokohama\/en\/wp-json\/wp\/v2\/comments?post=10722"}],"version-history":[{"count":9,"href":"https:\/\/dancebase.yokohama\/en\/wp-json\/wp\/v2\/pages\/10722\/revisions"}],"predecessor-version":[{"id":14077,"href":"https:\/\/dancebase.yokohama\/en\/wp-json\/wp\/v2\/pages\/10722\/revisions\/14077"}],"up":[{"embeddable":true,"href":"https:\/\/dancebase.yokohama\/en\/wp-json\/wp\/v2\/pages\/9046"}],"wp:attachment":[{"href":"https:\/\/dancebase.yokohama\/en\/wp-json\/wp\/v2\/media?parent=10722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}